{"id":1349,"date":"2025-03-14T17:52:35","date_gmt":"2025-03-14T16:52:35","guid":{"rendered":"https:\/\/onlyproject.org\/?p=1349"},"modified":"2025-04-14T16:11:15","modified_gmt":"2025-04-14T14:11:15","slug":"only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle","status":"publish","type":"post","link":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/","title":{"rendered":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle"},"content":{"rendered":"\n<p>L&rsquo;association AMM-Only Project est heureuse d\u2019annoncer le lancement de la Bourse des Pionniers et Pionni\u00e8res, un nouveau programme con\u00e7u pour soutenir des projets de recherche scientifique et m\u00e9dicale audacieux et \u00e0 fort potentiel d&rsquo;impact sur la myopathie de Duchenne ainsi que sur d\u2019autres maladies neuromusculaires pr\u00e9sentant des perspectives th\u00e9rapeutiques communes. Avec cette bourse, Only Project poursuit sa mission : acc\u00e9l\u00e9rer l\u2019innovation pour am\u00e9liorer la prise en charge et les traitements des patients. Ce soutien s\u2019inscrit dans la continuit\u00e9 de son engagement aupr\u00e8s d\u2019\u00e9quipes visionnaires et d\u00e9termin\u00e9es qui d\u00e9veloppent des innovations prometteuses, porteuses d\u2019un v\u00e9ritable espoir pour les patients atteints de myopathie de Duchenne.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La Bourse des Pionniers et Pionni\u00e8res propose un financement <strong>d\u00e9butant \u00e0 500 000 \u20ac <\/strong>par projet, pouvant atteindre <strong>jusqu\u2019\u00e0 2 millions d\u2019euros<\/strong> pour les initiatives pr\u00e9sentant un potentiel exceptionnel et n\u00e9cessitant de tels moyens pour atteindre leurs objectifs. Les projets seraient id\u00e9alement financ\u00e9s sur une p\u00e9riode de 2 ans. Toutefois, un financement \u00e0 plus long terme ou renouvelable pourrait \u00eatre envisag\u00e9 s\u2019il est d\u00fbment justifi\u00e9. Les projets s\u00e9lectionn\u00e9s par un processus exigeant b\u00e9n\u00e9ficieront du r\u00e9seau scientifique existant d\u2019Only Project, favorisant ainsi les collaborations et renfor\u00e7ant leur visibilit\u00e9 au sein de la communaut\u00e9 scientifique, en particulier celle d\u00e9di\u00e9e aux myopathies et aux maladies neuromusculaires.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Pr\u00e9sentation des experts du Conseil Scientifique <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"6\" src=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-10.png\" alt=\"\" class=\"wp-image-1286\"\/><\/figure>\n\n\n\n<p>Only Project a toujours mis un point d&rsquo;honneur \u00e0 garantir l&rsquo;excellence scientifique dans la s\u00e9lection des projets qu&rsquo;elle soutient. Pour structurer davantage cette d\u00e9marche et assurer un alignement optimal avec notre mission, un Conseil Scientifique a \u00e9t\u00e9 officiellement constitu\u00e9 \u00e0 l&rsquo;occasion du lancement de cette nouvelle bourse. Compos\u00e9 d\u2019experts europ\u00e9ens de renom dans le domaine des myopathies, il apporte une expertise pr\u00e9cieuse au Conseil d\u2019Administration dans l\u2019\u00e9valuation des subventions scientifiques. R\u00e9uni pour la premi\u00e8re fois \u00e0 Monaco en janvier 2025, il jouera un r\u00f4le cl\u00e9 dans l\u2019examen des candidatures \u00e0 la Bourse des Pionniers et Pionni\u00e8res.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Les membres du Conseil Scientifique&nbsp;sont :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>Karim Wahbi <\/strong>: Professeur des universit\u00e9s et cardiologue \u00e0 l\u2019Universit\u00e9 de Paris, coordonnateur du site de l\u2019h\u00f4pital Cochin pour le Centre de R\u00e9f\u00e9rence des Maladies Neuromusculaires.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>Annemieke Aartsma-Rus<\/strong> : Professeure de g\u00e9n\u00e9tique translationnelle au Leiden University Medical Center et professeure invit\u00e9e \u00e0 l\u2019Universit\u00e9 de Newcastle.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>Denis Furling<\/strong> : Directeur de recherche au CNRS bas\u00e9 \u00e0 Paris et responsable de l\u2019\u00e9quipe CRM, sp\u00e9cialis\u00e9e dans la myotonie de Steinert (DM1).&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>France Leturcq<\/strong> : Responsable du diagnostic g\u00e9n\u00e9tique des myopathies \u00e0 l\u2019h\u00f4pital Cochin, Paris.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>Nathalie Goemans<\/strong> : P\u00e9diatre et neurologue sp\u00e9cialiste des maladies neuromusculaires et de la r\u00e9\u00e9ducation, ancienne responsable du Centre de R\u00e9f\u00e9rence Neuromusculaire P\u00e9diatrique de l\u2019Universit\u00e9 de Louvain, actuellement professeure \u00e9m\u00e9rite.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Innovons Ensemble pour Transformer la Recherche<\/strong>&nbsp; <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"6\" src=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-8.png\" alt=\"\" class=\"wp-image-1278\"\/><\/figure>\n\n\n\n<p>Nous appelons les chercheuses et chercheurs anim\u00e9s par des id\u00e9es audacieuses et des approches novatrices \u00e0 candidater \u00e0 la Bourse des Pionniers et Pionni\u00e8res. Ensemble, acc\u00e9l\u00e9rons les d\u00e9couvertes et ouvrons de nouvelles perspectives pour am\u00e9liorer les traitements et la prise en charge des personnes atteintes des myopathies.&nbsp;<\/p>\n\n\n\n<p>Pour en savoir plus sur la Bourse des Pionniers et Pionni\u00e8res et le processus de candidature, cliquez <a href=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/04\/Pioneers-Grant-Description.pdf\">ici<\/a> (document en anglais).\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"7\" src=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-9-1024x7.png\" alt=\"\" class=\"wp-image-1280\" srcset=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-9-1024x7.png 1024w, https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-9-300x2.png 300w, https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-9-768x5.png 768w, https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/01\/image-9.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;association AMM-Only Project est heureuse d\u2019annoncer le lancement de la Bourse des Pionniers et Pionni\u00e8res, un nouveau programme con\u00e7u pour soutenir des projets de recherche scientifique et m\u00e9dicale audacieux et \u00e0 fort potentiel d&rsquo;impact sur&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[25,26],"class_list":["post-1349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-dmd-2","tag-duchenne-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;association AMM-Only Project est heureuse d\u2019annoncer le lancement de la Bourse des Pionniers et Pionni\u00e8res, un nouveau programme con\u00e7u pour soutenir des projets de recherche scientifique et m\u00e9dicale audacieux et \u00e0 fort potentiel d&rsquo;impact sur...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/\" \/>\n<meta property=\"og:site_name\" content=\"ONLY Project\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T16:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T14:11:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00e9a Dibong-Fournier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9a Dibong-Fournier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/\"},\"author\":{\"name\":\"L\u00e9a Dibong-Fournier\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#\\\/schema\\\/person\\\/7d6545c5ec8cf352a01b7d5100247d5e\"},\"headline\":\"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle\",\"datePublished\":\"2025-03-14T16:52:35+00:00\",\"dateModified\":\"2025-04-14T14:11:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/\"},\"wordCount\":599,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg\",\"keywords\":[\"DMD\",\"Duchenne\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/\",\"name\":\"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg\",\"datePublished\":\"2025-03-14T16:52:35+00:00\",\"dateModified\":\"2025-04-14T14:11:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#website\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/\",\"name\":\"ONLY Project\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onlyproject.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#organization\",\"name\":\"ONLY Project\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ONLY-PROJECT-COULEURS-RVB-VERTICAL.svg\",\"contentUrl\":\"https:\\\/\\\/onlyproject.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ONLY-PROJECT-COULEURS-RVB-VERTICAL.svg\",\"width\":1,\"height\":1,\"caption\":\"ONLY Project\"},\"image\":{\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onlyproject.org\\\/#\\\/schema\\\/person\\\/7d6545c5ec8cf352a01b7d5100247d5e\",\"name\":\"L\u00e9a Dibong-Fournier\",\"url\":\"https:\\\/\\\/onlyproject.org\\\/fr\\\/author\\\/leafournier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project","og_description":"L&rsquo;association AMM-Only Project est heureuse d\u2019annoncer le lancement de la Bourse des Pionniers et Pionni\u00e8res, un nouveau programme con\u00e7u pour soutenir des projets de recherche scientifique et m\u00e9dicale audacieux et \u00e0 fort potentiel d&rsquo;impact sur...","og_url":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/","og_site_name":"ONLY Project","article_published_time":"2025-03-14T16:52:35+00:00","article_modified_time":"2025-04-14T14:11:15+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"L\u00e9a Dibong-Fournier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L\u00e9a Dibong-Fournier","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#article","isPartOf":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/"},"author":{"name":"L\u00e9a Dibong-Fournier","@id":"https:\/\/onlyproject.org\/#\/schema\/person\/7d6545c5ec8cf352a01b7d5100247d5e"},"headline":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle","datePublished":"2025-03-14T16:52:35+00:00","dateModified":"2025-04-14T14:11:15+00:00","mainEntityOfPage":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/"},"wordCount":599,"commentCount":0,"publisher":{"@id":"https:\/\/onlyproject.org\/#organization"},"image":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#primaryimage"},"thumbnailUrl":"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg","keywords":["DMD","Duchenne"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/","url":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/","name":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle - ONLY Project","isPartOf":{"@id":"https:\/\/onlyproject.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#primaryimage"},"image":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#primaryimage"},"thumbnailUrl":"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg","datePublished":"2025-03-14T16:52:35+00:00","dateModified":"2025-04-14T14:11:15+00:00","breadcrumb":{"@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#primaryimage","url":"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg","contentUrl":"https:\/\/onlyproject.org\/wp-content\/uploads\/2025\/03\/louis-reed-pwcKF7L4-no-unsplash-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/onlyproject.org\/fr\/only-project-lance-la-bourse-des-pionniers-et-pionnieres-un-pari-audacieux-pour-une-recherche-innovante-et-des-projets-a-grande-echelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/onlyproject.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Only Project lance la Bourse\u00a0des Pionniers et Pionni\u00e8res\u00a0: un pari audacieux pour une recherche innovante et des projets \u00e0 grande \u00e9chelle"}]},{"@type":"WebSite","@id":"https:\/\/onlyproject.org\/#website","url":"https:\/\/onlyproject.org\/","name":"ONLY Project","description":"","publisher":{"@id":"https:\/\/onlyproject.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onlyproject.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onlyproject.org\/#organization","name":"ONLY Project","url":"https:\/\/onlyproject.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onlyproject.org\/#\/schema\/logo\/image\/","url":"https:\/\/onlyproject.org\/wp-content\/uploads\/2023\/06\/ONLY-PROJECT-COULEURS-RVB-VERTICAL.svg","contentUrl":"https:\/\/onlyproject.org\/wp-content\/uploads\/2023\/06\/ONLY-PROJECT-COULEURS-RVB-VERTICAL.svg","width":1,"height":1,"caption":"ONLY Project"},"image":{"@id":"https:\/\/onlyproject.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/onlyproject.org\/#\/schema\/person\/7d6545c5ec8cf352a01b7d5100247d5e","name":"L\u00e9a Dibong-Fournier","url":"https:\/\/onlyproject.org\/fr\/author\/leafournier\/"}]}},"_links":{"self":[{"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/posts\/1349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/comments?post=1349"}],"version-history":[{"count":21,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/posts\/1349\/revisions"}],"predecessor-version":[{"id":1448,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/posts\/1349\/revisions\/1448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/media\/1389"}],"wp:attachment":[{"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/media?parent=1349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/categories?post=1349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlyproject.org\/fr\/wp-json\/wp\/v2\/tags?post=1349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}